{"id":8736,"date":"2014-10-02T10:40:46","date_gmt":"2014-10-02T08:40:46","guid":{"rendered":"https:\/\/espazo.coop\/ugacota\/xornada-os-recursos-marinos-da-enseada-de-san-simon-2\/"},"modified":"2014-10-02T10:56:03","modified_gmt":"2014-10-02T08:56:03","slug":"xornada-os-recursos-marinos-da-enseada-de-san-simon","status":"publish","type":"post","link":"https:\/\/espazo.coop\/es\/noticias-del-cooperativismo\/xornada-os-recursos-marinos-da-enseada-de-san-simon\/","title":{"rendered":"Jornada: Los recursos marinos de la Ensenada de San Sim\u00f3n"},"content":{"rendered":"<p>La <a href=\"http:\/\/ardoraformacion.com\/\" target=\"_blank\" rel=\"noopener\">Cooperativa Ardora<\/a> nos hace llegar informaci\u00f3n sobre esta interesante actividad, programada para el pr\u00f3ximo 9 de octubre, que est\u00e1n organizando para el <a href=\"http:\/\/www.redondela-server.net\/\" target=\"_blank\" rel=\"noopener\">Ayuntamiento de Redondela<\/a>.<br \/>\nLa jornada se celebrar\u00e1 el jueves 9 de octubre, en horario de tarde (a partir de las 17:00hs) en el <a href=\"https:\/\/www.facebook.com\/MEIRANDE\" target=\"_blank\" rel=\"noopener\">Museo Meirande de Redondela<\/a>. El programa es muy variado e incluye el estreno del audiovisual \u00ab<strong><em> O choco, baixo as ondas de San Sim\u00f3n<\/em><\/strong>\u201d, varias ponencias en torno a los recursos marinos, un bodeg\u00f3n- degustaci\u00f3n y una exposici\u00f3n gr\u00e1fica.<br \/>\nLas personas interesadas pueden inscribirse <a href=\"https:\/\/docs.google.com\/forms\/d\/1NRtRB-o6ZT8gfPkKglyOX0aXdyzQ7EGi5YvVEOjwm6U\/viewform?c=0&amp;w=1\" target=\"_blank\" rel=\"noopener\">presionando en este enlace<\/a>.<\/p>\n<p>Puede consultarse el programa <a href=\"https:\/\/espazo.coop\/wp-content\/uploads\/2014\/10\/xornada_recursos_marinos_san_simon.pdf\" target=\"_blank\">presionando aqu\u00ed<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Cooperativa Ardora nos hace llegar informaci\u00f3n sobre esta interesante actividad, programada para el pr\u00f3ximo 9 de octubre, que est\u00e1n organizando para el Ayuntamiento de Redondela. La jornada se celebrar\u00e1 el jueves 9 de octubre, en horario de tarde (a partir de las 17:00hs) en <a href=\"https:\/\/espazo.coop\/es\/noticias-del-cooperativismo\/xornada-os-recursos-marinos-da-enseada-de-san-simon\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":5,"featured_media":8739,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[19,21],"tags":[1242,1244,1246,1245,1243,987],"class_list":["post-8736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-cooperativismo","category-ofertas-de-cooperativas","tag-ardora-es","tag-choco-es","tag-dieta-atlantica-es","tag-recursos-marino-es","tag-redondela-es","tag-xornada-es"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/espazo.coop\/wp-content\/uploads\/2014\/10\/sansimon.png","jetpack_shortlink":"https:\/\/wp.me\/p8lGby-2gU","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/8736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/comments?post=8736"}],"version-history":[{"count":0,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/8736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media\/8739"}],"wp:attachment":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media?parent=8736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/categories?post=8736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/tags?post=8736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}