{"id":7252,"date":"2014-02-20T13:45:04","date_gmt":"2014-02-20T12:45:04","guid":{"rendered":"https:\/\/espazo.coop\/?p=7252"},"modified":"2014-03-31T15:13:16","modified_gmt":"2014-03-31T13:13:16","slug":"premios-a-cooperacion-2014","status":"publish","type":"post","link":"https:\/\/espazo.coop\/es\/convocatoria\/premios-a-cooperacion-2014\/","title":{"rendered":"Premios a la cooperaci\u00f3n 2014"},"content":{"rendered":"<p><!--[if gte mso 9]><xml>\n <w:WordDocument>\n  <w:View>Normal<\/w:View>\n  <w:Zoom>0<\/w:Zoom>\n  <w:HyphenationZone>21<\/w:HyphenationZone>\n  <w:Compatibility>\n   <w:BreakWrappedTables\/>\n   <w:SnapToGridInCell\/>\n   <w:WrapTextWithPunct\/>\n   <w:UseAsianBreakRules\/>\n  <\/w:Compatibility>\n  <w:BrowserLevel>MicrosoftInternetExplorer4<\/w:BrowserLevel>\n <\/w:WordDocument>\n<\/xml><![endif]--><\/p>\n<p><!--[if gte mso 10]>\n\n\n<style>\n \/* Style Definitions *\/\n table.MsoNormalTable\n\t{mso-style-name:\"Tabla normal\";\n\tmso-tstyle-rowband-size:0;\n\tmso-tstyle-colband-size:0;\n\tmso-style-noshow:yes;\n\tmso-style-parent:\"\";\n\tmso-padding-alt:0cm 5.4pt 0cm 5.4pt;\n\tmso-para-margin:0cm;\n\tmso-para-margin-bottom:.0001pt;\n\tmso-pagination:widow-orphan;\n\tfont-size:10.0pt;\n\tfont-family:\"Times New Roman\";}\n<\/style>\n\n\n<![endif]--><\/p>\n<p>La <a href=\"http:\/\/traballoebenestar.xunta.es\/\" target=\"_blank\" rel=\"noopener\">Conseller\u00eda de Traballo e Benestar<\/a> convoc\u00f3 los premios a la cooperaci\u00f3n 2014.<\/p>\n<p><strong>Finalidad:<\/strong> Fomentar y difundir el cooperativismo, sus principios y valores, reconocer publicamente la labor que cooperativistas y otras personas e instituciones vienen haciendo a favor del desarrollo del movimiento cooperativo en Galicia.<\/p>\n<p><strong>Podr\u00e1n optar a estos premios:<\/strong> Las cooperativas, y las personas f\u00edsicas o jur\u00eddicas, p\u00fablicas o privadas, que realizasen una destacada labor en el campo del cooperativismo en la Comunidad Aut\u00f3noma gallega.<\/p>\n<p><strong>Modalidades:<\/strong><\/p>\n<p>\u2022 Premio a los <strong>valores cooperativos<\/strong>, dotado con 5.000 \u20ac<\/p>\n<p>\u2022 Premio al <strong>mejor proyecto cooperativo<\/strong>, dotado con 5.000 \u20ac<\/p>\n<p>\u2022 Premio a la <strong>promoci\u00f3n del cooperativismo<\/strong>, dotado con 5.000 \u20ac<\/p>\n<p>El <strong>plazo<\/strong> de presentaci\u00f3n de las solicitudes y de los trabajos acaba el <strong>15 de mayo de 2014<\/strong><\/p>\n<p>Descarga: <a href=\"https:\/\/espazo.coop\/wp-content\/uploads\/2014\/02\/Premios-\u00e1-Cooperaci\u00f3n-2014.pdf\">bases reguladoras de los Premios a la Cooperaci\u00f3n 2014<\/a><\/p>\n<p>El DOG n\u00ba 35, de 20 de febrero de 2014, es en el que se publica la Orden del 12 de febrero de 2014, que establece las bases reguladoras de los premios a la cooperaci\u00f3n 2014, estas bases fueron aprobadas por el Pleno del <a href=\"http:\/\/www.cooperativasdegalicia.com\/\" target=\"_blank\" rel=\"noopener\">Consello Galego de Cooperativas<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\">\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Conseller\u00eda de Traballo e Benestar convoc\u00f3 los premios a la cooperaci\u00f3n 2014. Finalidad: Fomentar y difundir el cooperativismo, sus principios y valores, reconocer publicamente la labor que cooperativistas y otras personas e instituciones vienen haciendo a favor del desarrollo del movimiento cooperativo en Galicia. <a href=\"https:\/\/espazo.coop\/es\/convocatoria\/premios-a-cooperacion-2014\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":7552,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20],"tags":[854],"class_list":["post-7252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-convocatoria","tag-premios-a-cooperacion-es"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/espazo.coop\/wp-content\/uploads\/2014\/02\/premiosCooperaci\u00f3n14.jpg","jetpack_shortlink":"https:\/\/wp.me\/p8lGby-1SY","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/7252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/comments?post=7252"}],"version-history":[{"count":0,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/7252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media\/7552"}],"wp:attachment":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media?parent=7252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/categories?post=7252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/tags?post=7252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}