{"id":29938,"date":"2020-06-05T08:46:18","date_gmt":"2020-06-05T06:46:18","guid":{"rendered":"https:\/\/espazo.coop\/?p=29938"},"modified":"2020-06-05T08:46:18","modified_gmt":"2020-06-05T06:46:18","slug":"fin-de-prazo-presentacion-solicitudes-pel-2020-o-xoves-11-de-xuno","status":"publish","type":"post","link":"https:\/\/espazo.coop\/es\/convocatoria\/fin-de-prazo-presentacion-solicitudes-pel-2020-o-xoves-11-de-xuno\/","title":{"rendered":"Fin de prazo presentaci\u00f3n solicitudes PEL 2020 o xoves 11 de xu\u00f1o"},"content":{"rendered":"<h1><strong>Fin de prazo presentaci\u00f3n solicitudes PEL 2020 o xoves 11\/06\/2020<\/strong><\/h1>\n<p>&nbsp;<\/p>\n<p>Desde o equipo t\u00e9cnico do Plan de Emprego Local lembran que <b>o prazo de presentaci\u00f3n de solicitudes \u00e1s axudas do Plan de Emprego Local (PEL 2020) remata o vindeiro xoves, d\u00eda 11 de xu\u00f1o, \u00e1s 14.00 horas<\/b>. As axudas que poden solicitar as pequenas e medianas empresas, microempresas e persoas aut\u00f3nomas son as seguintes:<\/p>\n<p>\u2022 PEL EMPRENDE INVESTIMENTO: Axudas de ata 17.500\u20ac (sen IVE) para contribuir \u00e1 consolidaci\u00f3n e ao fortalecemento do tecido empresarial nos concellos da provincia da Coru\u00f1a a trav\u00e9s do apoio ao investimento en bens inventariables (aplicaci\u00f3ns inform\u00e1ticas, maquinaria, mobiliario e equipos para procesos de informaci\u00f3n).<\/p>\n<p>\u2022 PEL PEMES CREACI\u00d3N E AMPLIACI\u00d3N do cadro de persoal: Axudas de ata o 70% dos custes de soldos e salarios e Seguridade Social para subvencionar o primeiro ano de contrataci\u00f3n dunha nova persoa traballadora.<\/p>\n<p>\u2022 PEL PEMES MANTEMENTO do cadro de persoal: Axudas de ata o 50% dos custes de soldos e salarios e Seguridade Social para subvencionar ao mantemento da persoa traballadora subvencionada ao abeiro de PEL PEMES CREACI\u00d3N E AMPLIACI\u00d3N 2019.<\/p>\n<p>As bases das axudas PEL 2020 poden consultarse no Bolet\u00edn Oficial da Provincia n\u00ba 29 do 12 de febreiro de 2020 ou na seguinte ligaz\u00f3n:\u00a0<a class=\"moz-txt-link-freetext\" href=\"https:\/\/bop.dicoruna.es\/bopportal\/publicado\/2020\/02\/12\/2020_0000000963.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/bop.dicoruna.es\/bopportal\/publicado\/2020\/02\/12\/2020_0000000963.pdf<\/a><\/p>\n<p>As solicitudes presentaranse de xeito telem\u00e1tico, a trav\u00e9s da aplicaci\u00f3n SUBTeL, que se pode atopar na p\u00e1xina web da Deputaci\u00f3n da Coru\u00f1a (<a href=\"https:\/\/www.dacoruna.gal\/dicoruna-subtel\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.dacoruna.gal\/dicoruna-subtel<\/a>).<\/p>\n<p>Tam\u00e9n na web <a href=\"https:\/\/emprego.dacoruna.gal\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/emprego.dacoruna.gal<\/a>\/ p\u00f3dese consultar a informaci\u00f3n actualizada do Plan de Emprego Local as\u00ed como o documento preguntas frecuentes (FAQ) referido \u00e1s bases.<\/p>\n<p>Para calquera d\u00fabida, aclaraci\u00f3n ou consulta contactar co equipo t\u00e9cnico do Plan de Emprego Local do Concello da Coru\u00f1a.<\/p>\n<div class=\"moz-signature\"><\/div>\n<div class=\"moz-signature\">\n<p>&#8212;<\/p>\n<table>\n<tbody>\n<tr>\n<td><a href=\"http:\/\/www.dacoruna.gal\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/www.dacoruna.gal\/files\/6514\/6166\/0012\/logo-fondo-azul-portada-empleo-recortado.PNG\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fin de prazo presentaci\u00f3n solicitudes PEL 2020 o xoves 11\/06\/2020 &nbsp; Desde o equipo t\u00e9cnico do Plan de Emprego Local lembran que o prazo de presentaci\u00f3n de solicitudes \u00e1s axudas do Plan de Emprego Local (PEL 2020) remata o vindeiro xoves, d\u00eda 11 de xu\u00f1o, <a href=\"https:\/\/espazo.coop\/es\/convocatoria\/fin-de-prazo-presentacion-solicitudes-pel-2020-o-xoves-11-de-xuno\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":29936,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20],"tags":[],"class_list":["post-29938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-convocatoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/espazo.coop\/wp-content\/uploads\/2020\/06\/PEL-EMPRENDE.jpg","jetpack_shortlink":"https:\/\/wp.me\/p8lGby-7MS","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/29938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/comments?post=29938"}],"version-history":[{"count":1,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/29938\/revisions"}],"predecessor-version":[{"id":29939,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/29938\/revisions\/29939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media\/29936"}],"wp:attachment":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media?parent=29938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/categories?post=29938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/tags?post=29938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}