{"id":29582,"date":"2020-04-24T13:34:02","date_gmt":"2020-04-24T11:34:02","guid":{"rendered":"https:\/\/espazo.coop\/?p=29582"},"modified":"2020-04-24T13:34:02","modified_gmt":"2020-04-24T11:34:02","slug":"continuamos-el-dialogo-con-las-administraciones-para-trasladar-demandas-de-las-cooperativas","status":"publish","type":"post","link":"https:\/\/espazo.coop\/es\/espazocoop\/continuamos-el-dialogo-con-las-administraciones-para-trasladar-demandas-de-las-cooperativas\/","title":{"rendered":"Continuamos el di\u00e1logo con las administraciones para trasladar demandas de las cooperativas"},"content":{"rendered":"<h1><strong>Continuamos o di\u00e1logo coas administraci\u00f3ns para trasladar demandas das cooperativas<\/strong><\/h1>\n<p>Estimadas compa\u00f1eiras e compa\u00f1eiros cooperativistas,<\/p>\n<p>Despois de m\u00e1is de cinco semanas na casa espero que v\u00f3s e as vosas familias, cooperativas e amizades esteades ben. Xa queda menos para a fin do confinamento e ver a luz que entra polas nosas fiestras.<\/p>\n<p>Neste tempo, que parecen meses no canto de semanas, dende Espazocoop tentamos acompa\u00f1arvos na traves\u00eda dun cami\u00f1o que nunca antes tiv\u00e9ramos que percorrer nin como empresas nin como persoas e aqu\u00ed seguimos.<\/p>\n<p>Entre as moitas actividades coas que seguimos, continuamos o papel de interlocutor coas diferentes administraci\u00f3ns (estatal, auton\u00f3mica e local) para trasladarlle as nosas demandas e a importancia de sa\u00edr xuntas, situando \u00e1s persoas no centro das decisi\u00f3ns, igual que no cooperativismo o levamos facendo dende sempre.<\/p>\n<p>A pasada semana, da man do Foro Galego pola Econom\u00eda Social, mantivemos unha xuntanza co conselleiro de Econom\u00eda, Emprego e Industria, Francisco Conde. Nela falamos da situaci\u00f3n na que se atopa o cooperativismo e o conxunto da econom\u00eda social galega. Falamos das perdas e das baixadas de facturaci\u00f3n; dos ceses de actividade e dos ERTES; dos sectores que se viron na obriga de paralizar toda a s\u00faa actividade e daqueles que tivemos que adaptar a nosa actividade, nun tempo r\u00e9cord, para poder seguir a prestar servizos e vender os nosos produtos. Mais tam\u00e9n puxemos de manifesto a importancia de nestes momentos manter o noso Know how, o saber facer, que \u00e9 o valor m\u00e1is importante que temos como sociedade e como econom\u00eda. Por \u00faltimo, fix\u00e9moslle chegar un documento con todas as demandas e necesidades da Econom\u00eda Social Galega.<\/p>\n<p>Acceso ao documento:\u00a0<a href=\"https:\/\/espazo.coop\/wp-content\/uploads\/2020\/04\/FOROESGAL-PROPOSTAS-DE-MEDIDAS-EXTRAORDINARIAS-ECONOMIA-SOCIAL-GALEGA_VF.pdf\">Propostas de Medidas Extraordinarias econom\u00eda social galega (ForoESGal)<\/a><\/p>\n<p>Pola s\u00faa banda, o conselleiro amosounos \u201co compromiso da Xunta coa econom\u00eda social, un modelo sustentable e igualitario, que promove emprego de calidade e que ser\u00e1 unha peza fundamental na reactivaci\u00f3n econ\u00f3mica de Galicia\u201d. Tam\u00e9n a vontade de analizar o documento de demandas e de manter o di\u00e1logo como ponte para seguir traballando.<\/p>\n<p>Seguimos traballando, sendo conscientes de que precisamos medidas no inmediato pois os tempos para moitas esg\u00f3tanse e os recursos dispo\u00f1ibles non son suficientes.<\/p>\n<p>Agradec\u00e9mosvos a vosa colaboraci\u00f3n, imprescindible para poder seguir avanzando, e agardamos poder vernos pronto.<\/p>\n<p>Son tempos de coidados.<\/p>\n<p>Ana Olveira Blanco<br \/>\nPresidenta da Uni\u00f3n de Cooperativas EspazoCoop<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuamos o di\u00e1logo coas administraci\u00f3ns para trasladar demandas das cooperativas Estimadas compa\u00f1eiras e compa\u00f1eiros cooperativistas, Despois de m\u00e1is de cinco semanas na casa espero que v\u00f3s e as vosas familias, cooperativas e amizades esteades ben. Xa queda menos para a fin do confinamento e ver <a href=\"https:\/\/espazo.coop\/es\/espazocoop\/continuamos-el-dialogo-con-las-administraciones-para-trasladar-demandas-de-las-cooperativas\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":29573,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,19],"tags":[],"class_list":["post-29582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espazocoop","category-noticias-del-cooperativismo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/espazo.coop\/wp-content\/uploads\/2020\/04\/balloon-898682_1920.jpg","jetpack_shortlink":"https:\/\/wp.me\/p8lGby-7H8","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/29582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/comments?post=29582"}],"version-history":[{"count":1,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/29582\/revisions"}],"predecessor-version":[{"id":29583,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/29582\/revisions\/29583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media\/29573"}],"wp:attachment":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media?parent=29582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/categories?post=29582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/tags?post=29582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}