{"id":19280,"date":"2017-09-12T15:24:12","date_gmt":"2017-09-12T13:24:12","guid":{"rendered":"https:\/\/espazo.coop\/?p=19280\/"},"modified":"2017-09-12T15:24:12","modified_gmt":"2017-09-12T13:24:12","slug":"rexenerando-colabora-con-emprendemento-coruna-impulsando-creactiva","status":"publish","type":"post","link":"https:\/\/espazo.coop\/es\/noticias-del-cooperativismo\/rexenerando-colabora-con-emprendemento-coruna-impulsando-creactiva\/","title":{"rendered":"Rexenerando colabora con Emprendemento Coru\u00f1a impulsando \u00abCreActiva\u00bb"},"content":{"rendered":"<p>As Xornadas \u201ccreActiva, arte e cultura como medio e opci\u00f3n de vida\u201d celebraranse no marco do Programa <strong>Emprendemento Coru\u00f1a<\/strong>, e ter\u00e1n lugar os pr\u00f3ximos d\u00edas <strong>15 e 16 de Setembro de 2017<\/strong> nas Instalaci\u00f3ns do centro municipal de co-working<strong> Accede Papagaio<\/strong>.<\/p>\n<p>O Programa Emprendemento Coru\u00f1a \u00e9 unha aposta por facilitar un espazo de encontro e xeracion de ideas, de asesoramento, formaci\u00f3n e axudas \u00e1 creaci\u00f3n de empresas e ao fomento da actividade emprendedora: innovadora, sostible, internacional e da econom\u00eda creativa; as\u00ed como de actividades informativas e de networking dirixidas a todas as persoas interesadas en emprender e entidades que est\u00e1n traballando no \u00e1mbito do emprendemento innovador e emerxente.<\/p>\n<h3><strong>CreActiva, arte e cultura como medio e opci\u00f3n de vida<\/strong><\/h3>\n<p>Xornadas para a xeraci\u00f3n de ideas, networking, detecci\u00f3n de necesidades e creaci\u00f3n de sinerxias entre os axentes que est\u00e1n revolucionando a econom\u00eda creativa a nivel local: artes pl\u00e1sticas, cultura, industria creativa, marketing dixital, animaci\u00f3n, videoxogos, publicidade, novas tecnolox\u00edas aplicadas \u00e1 creatividade, etc.<\/p>\n<h3><strong>Encontros dirixidos a iniciativas do sector cultural e da industria creativa<\/strong><\/h3>\n<h3><strong>Programa :<\/strong><\/h3>\n<p><strong>As experiencias que nos inspiran (en aberto)<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<h4><strong>Venres, 15 de setembro | 10:00 &#8211; 13:30<\/strong><\/h4>\n<ul>\n<li>Olga Osorio, realizadora e produtora de cine (Miss Movie)<\/li>\n<li>Manel Cr\u00e1neo, artista multidisciplinar e produtor cultural (Demo editorial e Planeta Mincha)<\/li>\n<li>Cecilia Portela, dese\u00f1adora de moda (Makta)<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<h4><strong>As redes que nos soste\u00f1en (inscrici\u00f3n previa)<\/strong><\/h4>\n<p><strong>Venres, 15 de setembro | 16:00 &#8211; 19:30<\/strong><\/td>\n<\/tr>\n<tr>\n<td>\n<h4><strong>As conexi\u00f3ns que nos impulsan (inscrici\u00f3n previa)<\/strong><\/h4>\n<p><strong>S\u00e1bado, 16 de setembro | 10:00 &#8211; 14:30<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Xornada coordinada por Rexenerando S. Coop. Galega<\/p>\n<table>\n<tbody>\n<tr>\n<td align=\"center\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScfTRDtxoNJLP3N-iBkcUkhT1z12Ckte5JJTyXZ8tEGLr2J6g\/viewform\" target=\"_blank\" rel=\"noopener\">Inscr\u00edbete aqu\u00ed<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>As Xornadas \u201ccreActiva, arte e cultura como medio e opci\u00f3n de vida\u201d celebraranse no marco do Programa Emprendemento Coru\u00f1a, e ter\u00e1n lugar os pr\u00f3ximos d\u00edas 15 e 16 de Setembro de 2017 nas Instalaci\u00f3ns do centro municipal de co-working Accede Papagaio. O Programa Emprendemento Coru\u00f1a <a href=\"https:\/\/espazo.coop\/es\/noticias-del-cooperativismo\/rexenerando-colabora-con-emprendemento-coruna-impulsando-creactiva\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":19278,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[19,21],"tags":[],"class_list":["post-19280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-cooperativismo","category-ofertas-de-cooperativas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/espazo.coop\/wp-content\/uploads\/2017\/09\/creActiva-banner.jpg","jetpack_shortlink":"https:\/\/wp.me\/p8lGby-50Y","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/19280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/comments?post=19280"}],"version-history":[{"count":1,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/19280\/revisions"}],"predecessor-version":[{"id":19281,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/19280\/revisions\/19281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media\/19278"}],"wp:attachment":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media?parent=19280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/categories?post=19280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/tags?post=19280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}