{"id":18832,"date":"2017-06-22T18:40:34","date_gmt":"2017-06-22T16:40:34","guid":{"rendered":"https:\/\/espazo.coop\/?p=18832\/"},"modified":"2017-06-30T13:18:29","modified_gmt":"2017-06-30T11:18:29","slug":"arbore-organiza-la-charla-cocina-y-alimentacion-sostenible-en-verano","status":"publish","type":"post","link":"https:\/\/espazo.coop\/es\/noticias-del-cooperativismo\/arbore-organiza-la-charla-cocina-y-alimentacion-sostenible-en-verano\/","title":{"rendered":"\u00c1rbore organiza la charla: \u00abCocina y Alimentaci\u00f3n Sostenible en Verano\u00bb"},"content":{"rendered":"<p><strong>\u00c1rbore Consumo Consciente<\/strong> organiza para o vindeiro Venres, <strong>30 de Xu\u00f1o<\/strong> \u00e1s 20 h. unha charla con Natalia Carrillo, a coci\u00f1eira de referencia para petiscos e doces en todo tipo de actividades.<\/p>\n<p>O obxectivo da charla \u00e9 falar sobre coci\u00f1a e alimentaci\u00f3n sostibles no ver\u00e1n mediante a <strong>presentaci\u00f3n <\/strong>do<strong> \u00abCaderno Sostible edici\u00f3n de Ver\u00e1n\u00bb<\/strong>, que Natalia preparou para \u00c1rbore, e que incl\u00fae:<br \/>\n&#8211; Produtos de tempada do ver\u00e1n<br \/>\n&#8211; Consellos para aforrar consumo e esforzo na coci\u00f1a<br \/>\n&#8211; Receitas e ideas<br \/>\n&#8211; Resolver as d\u00fabidas que poidan xurdir (Habilitarase un correo electr\u00f3nico para que Natalia responda consultas sobre o caderno ata o 30 de Setembro)<\/p>\n<p>As persoas que asistan \u00e1 charla recibiran de balde un exemplar do Caderno, que xa veredes, quedou fant\u00e1stico. A partires dese d\u00eda venderanse na tenda da cooperativa \u00c1rbore por 3\u20ac.<\/p>\n<p><strong>Prec\u00edsase confirmaci\u00f3n de asistencia<\/strong> posto que as prazas son limitadas, fac\u00e9deo en <a href=\"m&#97;&#105;&#x6c;&#x74;o:&#105;&#110;&#x66;&#x6f;&#64;a&#114;&#98;&#x6f;&#x72;e&#46;&#111;&#x72;&#x67;\">info&#64;a&#114;&#98;&#111;&#114;&#101;&#46;&#111;&#x72;&#x67;<\/a> ou na propia tenda (r\u00faa L\u00f3pez Mora 30 baixo, Vigo)<\/p>\n<p>A asistencia est\u00e1 aberta tanto a socias como non socias da cooperativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1rbore Consumo Consciente organiza para o vindeiro Venres, 30 de Xu\u00f1o \u00e1s 20 h. unha charla con Natalia Carrillo, a coci\u00f1eira de referencia para petiscos e doces en todo tipo de actividades. O obxectivo da charla \u00e9 falar sobre coci\u00f1a e alimentaci\u00f3n sostibles no ver\u00e1n <a href=\"https:\/\/espazo.coop\/es\/noticias-del-cooperativismo\/arbore-organiza-la-charla-cocina-y-alimentacion-sostenible-en-verano\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":18829,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[19,21],"tags":[],"class_list":["post-18832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-cooperativismo","category-ofertas-de-cooperativas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/espazo.coop\/wp-content\/uploads\/2017\/06\/presentacion_cadernos_sostibles_vrao.jpg","jetpack_shortlink":"https:\/\/wp.me\/p8lGby-4TK","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/18832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/comments?post=18832"}],"version-history":[{"count":1,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/18832\/revisions"}],"predecessor-version":[{"id":18833,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/18832\/revisions\/18833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media\/18829"}],"wp:attachment":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media?parent=18832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/categories?post=18832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/tags?post=18832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}