{"id":18661,"date":"2017-06-08T21:19:03","date_gmt":"2017-06-08T19:19:03","guid":{"rendered":"https:\/\/espazo.coop\/?p=18661\/"},"modified":"2017-06-08T21:19:03","modified_gmt":"2017-06-08T19:19:03","slug":"que-papel-queremos-jugar-como-cooperativas-o-entidades-de-economia-social","status":"publish","type":"post","link":"https:\/\/espazo.coop\/es\/noticias-del-cooperativismo\/que-papel-queremos-jugar-como-cooperativas-o-entidades-de-economia-social\/","title":{"rendered":"\u00bfQu\u00e9 papel queremos jugar como cooperativas o entidades de econom\u00eda social?"},"content":{"rendered":"<p class=\"western\">Por Celso G\u00e1ndara &#8211; Presidente de Espazocoop<\/p>\n<p><span lang=\"es-ES\">En este mes de mayo he tenido la oportunidad de participar en varias actos, que me han permitido reflexionar acerca de si tenemos un papel que desarrollar a mayores del desarrollo de nuestros negocios, en el caso de las empresas de la econom\u00eda social (cooperativas, sociedades laborales, centros especiales de empleo o empresas de inserci\u00f3n) o actividades y servicios en el caso de las organizaciones no lucrativas ( asociaciones, fundaciones,\u2026) <\/span><\/p>\n<p><span lang=\"es-ES\">El pasado <strong>23 de mayo<\/strong> 11 <\/span>Ministros de pa\u00edses europeos, incluida Espa\u00f1a, firmaron la <strong>Declaraci\u00f3n de Madrid<\/strong>, un documento que pretende situar al sector de la econom\u00eda social en el centro de las pol\u00edticas econ\u00f3micas europeas y lanzar una \u201ceconom\u00eda europea de la Econom\u00eda Social\u201d que permita impulsar su desarrollo.<\/p>\n<p><strong>\u00bfCu\u00e1l puede ser el impacto real de esto? <\/strong><\/p>\n<p>En primer lugar si no apareces como un sujeto en las pol\u00edticas no existes, esto tiene que ver con que la econom\u00eda social ser\u00e1 uno de los sujetos sobre los que se desarrollaran las pol\u00edticas de desarrollo econ\u00f3mico en Europa. Por lo tanto existir\u00e1 un Plan de desarrollo de la Econom\u00eda Social en Europa, al que se le asignar\u00e1 un presupuesto. Ello derivar\u00e1 en que existir\u00e1 un Plan de Econom\u00eda Social a nivel estatal. Manteniendo el efecto cascada, habr\u00e1 un Plan de la Econom\u00eda social a nivel Auton\u00f3mico. Estos planes determinar\u00e1n la composici\u00f3n, denominaci\u00f3n y funciones de las estructuras org\u00e1nicas de las diferentes administraciones p\u00fablicas. Con lo cual esto puede determinar cambios en la forma de funcionar y de agruparse por parte de las entidades que representamos a la sociedad civil.<\/p>\n<p>Desde este contexto creo que emerge con claridad, la necesidad y la oportunidad para que las entidades que conformamos la econom\u00eda social aunemos esfuerzos y con agilidad nos adaptemos al nuevo escenario que tenemos delante.<\/p>\n<p>Una incidencia pol\u00edtica de mayor impacto, pudiendo acceder a espacios en estos momentos restringidos a la representaci\u00f3n empresarial y sindical sin lugar a dudas nos podr\u00eda permitir un impacto mayor y situar la econom\u00eda social en la agenda pol\u00edtica.<\/p>\n<p>La intercooperaci\u00f3n y el intercambio comercial (mercado social) entre entidades que conforman la econom\u00eda social, generar\u00eda un mayor desarrollo del sector y al mismo tiempo identidad y m\u00fasculo.<\/p>\n<p>El<strong> 2 de Junio<\/strong> tuvo lugar la<strong> primera asamblea de Espazo Coop<\/strong>, que es la Uni\u00f3n de cooperativas de Galicia, desues de la fusi\u00f3n de tres organizaciones que representaban al cooperativismo. En si mismo ya es un hecho rese\u00f1able hablar de procesos de fusi\u00f3n e integraci\u00f3n en Galicia. Adem\u00e1s quer\u00eda destacar dos elementos, que pueden ser una oportunidad en los pr\u00f3ximos a\u00f1os:<\/p>\n<ol>\n<li>La tramitaci\u00f3n de la Ley de contratos del sector p\u00fablico, que se est\u00e1 tramitando en el Congreso de los diputados y que puede abrir de verdad un espacio para las clausulas sociales, tal y como recoge la directiva europea.<\/li>\n<li>La necesidad de incrementar dimesi\u00f3n, generando econom\u00edas de escala para poder acceder a nuevos servicios, nuevos mercados, ser m\u00e1s eficientes, abordar la innovaci\u00f3n etc<\/li>\n<\/ol>\n<p>Existen riesgos serios de podernos quedar fuera, o tener presencia residual dentro del mercado p\u00fablico. Las licitaciones cada vez son de lotes m\u00e1s grandes que est\u00e1n impidiendo el acceso de las entidades de econom\u00eda social, dado nuestro peque\u00f1o tama\u00f1o, y nos hacen perder oportunidades. El establecimiento de diversos tipos de alianzas o integraciones son una herramienta para poder aprovechar mejor estas oportunidades.<\/p>\n<p>En los mercados privados, el visibilizar que somos entidades de econom\u00eda social puede ser junto con productos y servicios con buenas propuestas de valor factores que nos ayuden a ser sostenibles a largo plazo. La necesidad de que surjan referentes y liderazgos dentro de diferentes sectores, que hagan de tractores del sector seguramente ayudar\u00eda al desarrollo del mismo.<\/p>\n<p>Tenemos conocimiento y si no, lo sabemos buscar, pero como dec\u00eda Suso de Toro, en el acto de presentaci\u00f3n de Espazocoop necesitamos \u201cdisposici\u00f3n\u201d. Esa frase me trajo muchas im\u00e1genes de mi infancia. Mi madre me la sol\u00eda decir\u2026.\u201d Un poco m\u00e1s de disposici\u00f3n Celso\u201d Pues eso, creo que las personas que estamos en movimientos vinculados a la econom\u00eda social, estamos llamados a \u201cdisponernos\u201d a abordar los retos comunes del futuro desde una entidad que nos agrupe y que nos visibilice delante de la sociedad. Los aspectos espec\u00edficos de cada colectivo ya est\u00e1n siendo abordados desde cada entidad representativa.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Celso G\u00e1ndara &#8211; Presidente de Espazocoop En este mes de mayo he tenido la oportunidad de participar en varias actos, que me han permitido reflexionar acerca de si tenemos un papel que desarrollar a mayores del desarrollo de nuestros negocios, en el caso de <a href=\"https:\/\/espazo.coop\/es\/noticias-del-cooperativismo\/que-papel-queremos-jugar-como-cooperativas-o-entidades-de-economia-social\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":18429,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[19],"tags":[],"class_list":["post-18661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-cooperativismo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/espazo.coop\/wp-content\/uploads\/2017\/05\/representaci\u00f3n-galega-na-Conferencia-europea-de-econom\u00eda-social-.jpg","jetpack_shortlink":"https:\/\/wp.me\/p8lGby-4QZ","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/18661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/comments?post=18661"}],"version-history":[{"count":1,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/18661\/revisions"}],"predecessor-version":[{"id":18662,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/18661\/revisions\/18662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media\/18429"}],"wp:attachment":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media?parent=18661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/categories?post=18661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/tags?post=18661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}