{"id":17994,"date":"2017-09-01T11:33:01","date_gmt":"2017-09-01T09:33:01","guid":{"rendered":"https:\/\/espazo.coop\/?p=17994\/"},"modified":"2017-09-01T13:47:09","modified_gmt":"2017-09-01T11:47:09","slug":"formacion-comercial-para-fortalecer-a-las-cooperativas-inicio-en-mayo","status":"publish","type":"post","link":"https:\/\/espazo.coop\/es\/espazocoop\/formacion-comercial-para-fortalecer-a-las-cooperativas-inicio-en-mayo\/","title":{"rendered":"Taller: \u00abFormaci\u00f3n comercial para fortalecer a las cooperativas\u00bb | Nueva sesi\u00f3n 8 de septiembre"},"content":{"rendered":"<p>En septiembre Espazocoop retoma el curso FORMACI\u00d3N COMERCIAL PARA FORTALECER A LAS COOPERATIVAS.<\/p>\n<p>La uni\u00f3n celebra la pr\u00f3xima sesi\u00f3n el viernes 8 de septiembre en Santiago de Compostela, en la que iniciamos el 2\u00ba bloque tem\u00e1tico : Divulgaci\u00f3n y puesta en pr\u00e1ctica de habilidades y herramientas operativas para el avance de los procesos y estrategias de comercializaci\u00f3n de las cooperativas participantes.<\/p>\n<p>Se trata de una capacitaci\u00f3n libre de costes para las cooperativas participantes que se desarrolla en modalidad presencial.<\/p>\n<ul>\n<li>En este curso contamos con personal formador especializado y experimentado en el \u00e1rea comercial:<\/li>\n<\/ul>\n<p>&#8211; Roberto P\u00e9rez Mariju\u00e1n y Juan Jos\u00e9 Romero ( Suma Importancia) : 12 de mayo, 9 de junio y 7 de julio.<\/p>\n<p>&#8211; Silvia Lobato Muriente (WEDU Sociedad\u00a0y Educaci\u00f3n WEDU): 8 y 29 de septiembre.<\/p>\n<ul>\n<li>Tiene una duraci\u00f3n de 20 horas (distribuido en 5 sesiones, una cita mensual)<\/li>\n<li>Queremos trabajar en aspectos de gesti\u00f3n as\u00ed como en las habilidades de el \u00e1mbito comercial de las cooperativas.<\/li>\n<li>Analizaremos y especificaremos las medidas necesarias en el sistema comercial, e implementaremos las competencias y herramientas para llevar a cabo las estrategias que contribuir\u00e1n a la mejora.<\/li>\n<li>La actividad formativa se desarrolla en horario de ma\u00f1ana, de 10 a 14 h.<\/li>\n<li>Fechas de las sesiones: 12 de mayo, 9 de junio, 7 de julio, 8 de septiembre y 29 de septiembre de 2017.<\/li>\n<li>Lugar de celebraci\u00f3n: Santiago de Compostela &#8211; Centro de la Red Eusumo en la Asociaci\u00f3n Gallega de Cooperativas Agroalimentarias (Agaca). R\u00faa Tomi\u00f1o 22 entrech\u00e1n.<\/li>\n<li>Las vacantes se limitan a un m\u00e1ximo de 20 participantes, con prioridad de asistencia de las cooperativas asociadas, y la inscripci\u00f3n se puede realizar al curso completo o por sesiones individuales.<\/li>\n<\/ul>\n<p>PROGRAMA:\u00a0<a href=\"https:\/\/espazo.coop\/wp-content\/uploads\/2017\/04\/Formacion-\u00c1rea-Comercial_espazocoop-2017.pdf\">Formaci\u00f3n comercial para fortalecer \u00e1s cooperativas\u00a0<\/a>INSCRICI\u00d3N:\u00a0<a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfJoIFagjLqsR_wih3LqPTCbXCml8BiOWiW_fio3-ieWkcZ4Q\/viewform\" target=\"_blank\" rel=\"noopener\">Aqu\u00ed<\/a><\/p>\n<p>[Esta actividade est\u00e1 no marco da programaci\u00f3n de actividades da Rede Eusumo: Fomento do Cooperativismo e da Econom\u00eda Social, para o ano 2017.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En septiembre Espazocoop retoma el curso FORMACI\u00d3N COMERCIAL PARA FORTALECER A LAS COOPERATIVAS. La uni\u00f3n celebra la pr\u00f3xima sesi\u00f3n el viernes 8 de septiembre en Santiago de Compostela, en la que iniciamos el 2\u00ba bloque tem\u00e1tico : Divulgaci\u00f3n y puesta en pr\u00e1ctica de habilidades y <a href=\"https:\/\/espazo.coop\/es\/espazocoop\/formacion-comercial-para-fortalecer-a-las-cooperativas-inicio-en-mayo\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":17909,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,26,19],"tags":[],"class_list":["post-17994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espazocoop","category-formacion-coop","category-noticias-del-cooperativismo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/espazo.coop\/wp-content\/uploads\/2017\/04\/cartel_formaci\u00f3n_comercial_espazocoop.png","jetpack_shortlink":"https:\/\/wp.me\/p8lGby-4Ge","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/17994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/comments?post=17994"}],"version-history":[{"count":5,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/17994\/revisions"}],"predecessor-version":[{"id":19230,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/17994\/revisions\/19230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media\/17909"}],"wp:attachment":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media?parent=17994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/categories?post=17994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/tags?post=17994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}