{"id":17440,"date":"2017-03-03T18:12:16","date_gmt":"2017-03-03T17:12:16","guid":{"rendered":"https:\/\/espazo.coop\/?p=17440\/"},"modified":"2017-03-03T18:13:00","modified_gmt":"2017-03-03T17:13:00","slug":"la-economia-social-y-solidaria-crece-y-se-renueva-portal-web","status":"publish","type":"post","link":"https:\/\/espazo.coop\/es\/noticias-del-cooperativismo\/la-economia-social-y-solidaria-crece-y-se-renueva-portal-web\/","title":{"rendered":"La econom\u00eda social y solidaria crece | Nuevo portal web"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p><strong>Espazocoop Uni\u00f3n de Cooperativas Galegas somos parte da Rede de Econom\u00eda Alternativa e Solidaria a trav\u00e9s da Rede galega (Reas Galicia), xunto a m\u00e1is entidades:<\/strong><\/p>\n<p><em><strong>Las m\u00e1s de 500 entidades que forman parte de REAS generan 379 millones de euros de ingresos anuales y cuentan con la participaci\u00f3n de m\u00e1s de 38.000 personas. En 1997 naci\u00f3 el portal web economiasolidaria.org para visibilizar estas redes y movimientos sociales por una econom\u00eda justa, ecol\u00f3gica, social y solidaria. Ahora REAS quiere renovarlo para que tenga mayor incidencia social y pol\u00edtica y para ello han lanzado una campa\u00f1a de crowdfunding.<\/strong><\/em><\/p>\n<p>En la \u00faltima d\u00e9cada la econom\u00eda social y solidaria se ha consolidado con una alternativa s\u00f3lida y estable. Actualmente, genera el 10% de PIB en el Estado espa\u00f1ol y da empleo a 2,2 millones de personas. Su apuesta por poner las personas en el centro se traduce en la generaci\u00f3n de 190.000 puestos de trabajo en los \u00faltimos a\u00f1os, con un 80% de contratos indefinidos.<\/p>\n<p>La econom\u00eda solidaria, en concreto, ha irrumpido en sectores estrat\u00e9gicos como la energ\u00eda, la banca o las telecomunicaciones, y despierta el inter\u00e9s de cada vez m\u00e1s personas. Las m\u00e1s de 500 entidades y empresas que forman parte de REAS -Red de Redes de Econom\u00eda Alternativa y Solidaria- generan 379 millones de euros de ingresos anuales y cuentan con la participaci\u00f3n de m\u00e1s de 38.000 personas, 8.500 contratadas.<\/p>\n<p>Para hacer frente a estos nuevos retos hacen falta herramientas a su altura, afirman desde REAS. Por ello, las personas responsables de REAS han emprendido la renovaci\u00f3n del portal web <a href=\"http:\/\/www.economiasolidaria.org\/\" target=\"_blank\" rel=\"noopener\">www.economiasolidaria.org<\/a> para que tenga mayor incidencia social y pol\u00edtica.<\/p>\n<p>La web de la econom\u00eda solidaria surgi\u00f3 en 1997 para visibilizar las redes y movimientos sociales por una econom\u00eda justa, ecol\u00f3gica, social y solidaria. El portal recibe m\u00e1s de 650.000 visitas al a\u00f1o, aloja m\u00e1s de 10.000 contenidos, y m\u00e1s de 28.000 personas y organizaciones est\u00e1n suscritas al bolet\u00edn mensual.<\/p>\n<p>Para poder financiar la renovaci\u00f3n de esta plataforma web lanzaron este martes una <a href=\"https:\/\/www.goteo.org\/project\/nuevo-portal-web-de-la-economia-solidaria\" target=\"_blank\" rel=\"noopener\">campa\u00f1a de crowdfunding<\/a> a trav\u00e9s de la plataforma Goteo que estar\u00e1 activa del 27 de febrero al 7 de abril de 2017. El objetivo m\u00ednimo son 19.000 euros y el \u00f3ptimo 25.500.<\/p>\n<p>\u201cEl objetivo es consolidarlo como el portal tem\u00e1tico m\u00e1s importante de la econom\u00eda solidaria en los territorios del Estado espa\u00f1ol y de habla castellana\u201d, afirman. La nueva plataforma web cambiar\u00e1 de estructura y de dise\u00f1o gr\u00e1fico para responder a los nuevos retos que tiene el movimiento social de la econom\u00eda solidaria.<\/p>\n<p>\u201cA la vez -a\u00f1aden-, queremos desplegarnos y compartir contenidos con otros dos espacios que van a tener gran importancia: el espacio de comunicaci\u00f3n e incidencia social y pol\u00edtica de REAS con sus 18 redes y del portal del mercado social (<a href=\"http:\/\/mercadosocial.net\/\" target=\"_blank\" rel=\"noopener\">mercadosocial.net<\/a>) con un gran cat\u00e1logo de entidades, productos y servicios para ejercer un consumo responsable e informaci\u00f3n e como participar en cada territorio\u201d.<\/p>\n<div class=\"video-shortcode\"><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" width=\"1100\" height=\"619\" src=\"https:\/\/www.youtube.com\/embed\/PtXwEJO9Wl4?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/div>\n<p>La filosof\u00eda de la econom\u00eda solidaria se recoge en la <a href=\"http:\/\/www.economiasolidaria.org\/carta.php\" target=\"_blank\" rel=\"noopener\">Carta de Principios de la Econom\u00eda Solidaria<\/a> y se resume en seis grandes principios: equidad, trabajo, sostenibilidad ambiental, cooperaci\u00f3n, sin fines lucrativos y compromiso con el entorno.<\/p>\n<p><a href=\"http:\/\/arainfo.org\/la-economia-social-y-solidaria-crece-y-se-renueva\/\" target=\"_blank\" rel=\"noopener\">Fuente Arainfo<\/a><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":17442,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[19],"tags":[],"class_list":["post-17440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-cooperativismo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/espazo.coop\/wp-content\/uploads\/2017\/03\/imagen_goteo_tx.jpg","jetpack_shortlink":"https:\/\/wp.me\/p8lGby-4xi","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/17440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/comments?post=17440"}],"version-history":[{"count":4,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/17440\/revisions"}],"predecessor-version":[{"id":17448,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/posts\/17440\/revisions\/17448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media\/17442"}],"wp:attachment":[{"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/media?parent=17440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/categories?post=17440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espazo.coop\/es\/wp-json\/wp\/v2\/tags?post=17440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}